{"id":2,"date":"2021-03-09T15:54:05","date_gmt":"2021-03-09T14:54:05","guid":{"rendered":"https:\/\/progetto-demo.wpmultisite.unimi.it\/?page_id=2"},"modified":"2026-02-26T10:29:24","modified_gmt":"2026-02-26T09:29:24","slug":"homepage","status":"publish","type":"page","link":"https:\/\/mermaid.unimi.it\/it\/","title":{"rendered":"Homepage"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:650px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-black-background-color has-background-dim-30 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1311\" class=\"wp-block-cover__image-background wp-image-1092\" alt=\"\" src=\"https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2024\/05\/hero.jpeg\" style=\"object-position:48% 47%\" data-object-fit=\"cover\" data-object-position=\"48% 47%\" srcset=\"https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2024\/05\/hero.jpeg 1920w, https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2024\/05\/hero-600x410.jpeg 600w, https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2024\/05\/hero-1024x699.jpeg 1024w, https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2024\/05\/hero-768x524.jpeg 768w, https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2024\/05\/hero-1536x1049.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-xlarge-font-size\" style=\"font-style:italic;font-weight:700\"><br>&#8230;<em>lieto chi l&#8217;ode, e ricco di molta scienza poi parte.<\/em><\/h3>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-right has-white-color has-text-color has-large-font-size\"><em>Odissea<\/em> XII, 188<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-white-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/mermaid.unimi.it\/it\/il-progetto\/\" style=\"border-radius:100px;color:#1d6359\">Scopri il progetto<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background\" style=\"background-color:#1d6359\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color\">Notizie<\/h2>\n\n\n<div class=\"article__list\"><article role=\"article\" id=\"post-1681\" class=\"post-1681 post type-post status-publish format-standard has-post-thumbnail hentry category-news-it\">\n    <div class=\"article__inner\">\n                    <figure class=\"article__image\">\n                <a href=\"https:\/\/mermaid.unimi.it\/it\/2026\/03\/19\/saperi-su-misura-nel-cantiere-del-progetto-mermaid\/\" title=\"Link a Saperi su misura: nel cantiere del progetto MERMAID\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"150\" src=\"https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2026\/03\/Banner-360x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" \/>                <\/a>\n            <\/figure>\n                <div class=\"article__content\">\n\n                            <span class=\"article__type\">\n                                                            News                <\/span>\n            \n            \n                        <div class=\"article__title\"><a href=\"https:\/\/mermaid.unimi.it\/it\/2026\/03\/19\/saperi-su-misura-nel-cantiere-del-progetto-mermaid\/\">Saperi su misura: nel cantiere del progetto MERMAID<\/a><\/div>\n            <p>In occasione della Giornata della Ricerca Dipartimentale di Studi Letterari, Filologici e Linguistici dell&#8217;Universit\u00e0 degli Studi di Milano, Luca Sacchi, Matteo Cesena e Marta Milazzo hanno presentato un intervento illustrando...<\/p>\n            <a class=\"more__link\" href=\"https:\/\/mermaid.unimi.it\/it\/2026\/03\/19\/saperi-su-misura-nel-cantiere-del-progetto-mermaid\/\" aria-label=\"Leggi tutto\">\n                Leggi tutto            <\/a>\n                    <\/div>\n    <\/div>\n<\/article>\n<article role=\"article\" id=\"post-1567\" class=\"post-1567 post type-post status-publish format-standard has-post-thumbnail hentry category-news-it\">\n    <div class=\"article__inner\">\n                    <figure class=\"article__image\">\n                <a href=\"https:\/\/mermaid.unimi.it\/it\/2025\/12\/23\/mermaid-closing-conference\/\" title=\"Link a Convegno conclusivo MERMAID\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"127\" src=\"https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2025\/12\/banner-1-360x127.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" \/>                <\/a>\n            <\/figure>\n                <div class=\"article__content\">\n\n                            <span class=\"article__type\">\n                                                            News                <\/span>\n            \n            \n                        <div class=\"article__title\"><a href=\"https:\/\/mermaid.unimi.it\/it\/2025\/12\/23\/mermaid-closing-conference\/\">Convegno conclusivo MERMAID<\/a><\/div>\n            <p>Il 12 e 13 gennaio si terr\u00e0 a Milano il convegno conclusivo del PRIN 2022 MERMAID, intitolato \u00abLe miscellanee romanze medievali come dispositivi didattici: risultati del censimento e prospettive di...<\/p>\n            <a class=\"more__link\" href=\"https:\/\/mermaid.unimi.it\/it\/2025\/12\/23\/mermaid-closing-conference\/\" aria-label=\"Leggi tutto\">\n                Leggi tutto            <\/a>\n                    <\/div>\n    <\/div>\n<\/article>\n<article role=\"article\" id=\"post-1556\" class=\"post-1556 post type-post status-publish format-standard has-post-thumbnail hentry category-news-it\">\n    <div class=\"article__inner\">\n                    <figure class=\"article__image\">\n                <a href=\"https:\/\/mermaid.unimi.it\/it\/2025\/12\/16\/forme-di-devozione-nelle-miscellanee-didattiche-romanze\/\" title=\"Link a Forme di devozione nelle miscellanee didattiche romanze\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"150\" src=\"https:\/\/mermaid.unimi.it\/wp-content\/uploads\/sites\/105\/2025\/12\/banner-360x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" \/>                <\/a>\n            <\/figure>\n                <div class=\"article__content\">\n\n                            <span class=\"article__type\">\n                                                            News                <\/span>\n            \n            \n                        <div class=\"article__title\"><a href=\"https:\/\/mermaid.unimi.it\/it\/2025\/12\/16\/forme-di-devozione-nelle-miscellanee-didattiche-romanze\/\">Forme di devozione nelle miscellanee didattiche romanze<\/a><\/div>\n            <p>Nell\u2019ambito del convegno internazionale \u00abAttraversamenti e frontiere della Letteratura religiosa\u00bb tenutosi all\u2019Universit\u00e0 di Padova, Luca Sacchi ha presentato una comunicazione dedicata alle\u00a0forme\u00a0e alle\u00a0funzioni\u00a0dei testi religiosi inseriti pi\u00f9 di frequente entro...<\/p>\n            <a class=\"more__link\" href=\"https:\/\/mermaid.unimi.it\/it\/2025\/12\/16\/forme-di-devozione-nelle-miscellanee-didattiche-romanze\/\" aria-label=\"Leggi tutto\">\n                Leggi tutto            <\/a>\n                    <\/div>\n    <\/div>\n<\/article>\n<\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-2 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-primary-color has-white-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/mermaid.unimi.it\/it\/news\/\" style=\"border-radius:100px\">Tutte le notizie<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">Contatti<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center\">Luca Sacchi, PhD<\/h4>\n\n\n\n<p class=\"has-text-align-center\">Principal Investigator<br>Dipartimento di Studi Letterari, Filologici e Linguistici<br>Universit\u00e0 degli Studi di Milano<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>E-mail<\/strong>:&nbsp;<a href=\"mailto:luca.sacchi@unimi.it\">luca.sacchi@unimi.it<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center\">Matteo Milani, PhD<\/h4>\n\n\n\n<p class=\"has-text-align-center\">Dipartimento di Lingue e Letterature straniere<br>e Culture moderne<br>Universit\u00e0 di Torino<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>E-mail<\/strong>:&nbsp;<a href=\"mailto:matteo.milani@unito.it\">matteo.milani@unito.it<\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Notizie Contatti Luca Sacchi, PhD Principal InvestigatorDipartimento di Studi Letterari, Filologici e LinguisticiUniversit\u00e0 degli Studi di Milano E-mail:&nbsp;luca.sacchi@unimi.it Matteo Milani, PhD Dipartimento di Lingue e Letterature stranieree Culture moderneUniversit\u00e0 di Torino E-mail:&nbsp;matteo.milani@unito.it<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":900,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/pages\/2"}],"collection":[{"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":40,"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":1657,"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/pages\/2\/revisions\/1657"}],"wp:attachment":[{"href":"https:\/\/mermaid.unimi.it\/it\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}